{"id":11739,"date":"2013-08-15T08:00:13","date_gmt":"2013-08-15T08:00:13","guid":{"rendered":"http:\/\/dinostorm.com\/aumente-as-habilidades-do-seu-ranger-de-uma-maneira-inovadora-adquira-geis-de-poder-2"},"modified":"2013-08-15T08:00:13","modified_gmt":"2013-08-15T08:00:13","slug":"aumente-as-habilidades-do-seu-ranger-de-uma-maneira-inovadora-adquira-geis-de-poder","status":"publish","type":"post","link":"https:\/\/dinostorm.com\/pt-br\/aumente-as-habilidades-do-seu-ranger-de-uma-maneira-inovadora-adquira-geis-de-poder\/","title":{"rendered":"Aumente as habilidades do seu Ranger de uma maneira inovadora: Adquira G\u00e9is de Poder!"},"content":{"rendered":"<div>N\u00f3s adicionamos uma maneira nova de aumentar as habilidades do seu Ranger: Abra a janela do seu Perfil e procure pelos novos &#8220;G\u00e9is de Poder&#8221;.<\/div>\n<h1 style=\"margin-top: 32px; margin-bottom: 28px; font-size: 25px;\">Aumente e melhore as habilidades do Seu Ranger com G\u00e9is de Poder<\/h1>\n<div style=\"margin-right: 20px; float: left; width: 242px; text-align: left;\">\n<h3>5 Efeitos diferentes dos<br \/>\nG\u00e9is de Poder<\/h3>\n<div style=\"text-align: justify;\">Se voc\u00ea quiser proteger os seus edif\u00edcios ou simplesmente ganhar mais XP, existe um Gel de poder para isso.<\/div>\n<\/div>\n<div style=\"margin-left: 20px; margin-right: 20px; float: left; width: 242px; text-align: left;\">\n<h3>Use todos os efeitos de uma s\u00f3 vez<\/h3>\n<div style=\"text-align: justify;\">N\u00e3o se preocupe com efeitos colaterais \u2013 todos os tipos de G\u00e9is podem ser usados ao mesmo tempo.<\/div>\n<\/div>\n<div style=\"margin-left: 20px; float: left; width: 242px; text-align: left;\">\n<h3>Some os efeitos para ter o<br \/>\npoder m\u00e1ximo<\/h3>\n<div style=\"text-align: justify;\">O efeito de cada tipo de Gel pode ser somado. Por exemplo, voc\u00ea pode ter\u00a0 100% de Porta Moedas!<\/div>\n<\/div>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-8372 colorbox-11739\" style=\"padding-top: 32px; padding-left: 40px;\" alt=\"Dino Storm \u2013 Power Gels\" src=\"http:\/\/dinostorm.com\/wp-content\/uploads\/2014\/08\/dino.storm_.power_.gels_.window.jpg\" width=\"672\" height=\"427\" srcset=\"https:\/\/dinostorm.com\/wp-content\/uploads\/2014\/08\/dino.storm_.power_.gels_.window.jpg 672w, https:\/\/dinostorm.com\/wp-content\/uploads\/2014\/08\/dino.storm_.power_.gels_.window-300x191.jpg 300w\" sizes=\"auto, (max-width: 672px) 100vw, 672px\" \/><\/p>\n<h1 style=\"clear: both; margin-top: 36px; margin-bottom: 48px; font-size: 25px;\">Apresentando os Cinco novos G\u00e9is de Poder \u2013 Eles s\u00e3o muito eficazes!<\/h1>\n<div style=\"margin-right: 30px; float: left; width: 373px; text-align: left;\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-8361 colorbox-11739\" style=\"padding-top: 12px;\" alt=\"Experience Gain Power Gel\" src=\"http:\/\/dinostorm.com\/wp-content\/uploads\/2014\/08\/powergel_experience_gain.png\" width=\"100\" height=\"100\" srcset=\"https:\/\/dinostorm.com\/wp-content\/uploads\/2014\/08\/powergel_experience_gain.png 100w, https:\/\/dinostorm.com\/wp-content\/uploads\/2014\/08\/powergel_experience_gain-36x36.png 36w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><\/p>\n<h2 style=\"padding-top: 1px;\">Ganho de Experi\u00eancia<\/h2>\n<div>Aumeta os pontos de experi\u00eancia em 90% ao completar tarefas ou ao derrotar inimigos.<\/div>\n<\/div>\n<div style=\"margin-left: 30px; float: left; width: 373px; text-align: left;\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-8362 colorbox-11739\" style=\"padding-top: 12px;\" alt=\"Item Protection Power Gel\" src=\"http:\/\/dinostorm.com\/wp-content\/uploads\/2014\/08\/powergel_item_protection.png\" width=\"100\" height=\"100\" srcset=\"https:\/\/dinostorm.com\/wp-content\/uploads\/2014\/08\/powergel_item_protection.png 100w, https:\/\/dinostorm.com\/wp-content\/uploads\/2014\/08\/powergel_item_protection-36x36.png 36w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><\/p>\n<h2 style=\"padding-top: 1px;\">Porta Moedas<\/h2>\n<div>Garante a possibilidade de at\u00e9 100% ,de manter todos os Dino d\u00f3lares, quando for derrotado em combate.<\/div>\n<\/div>\n<div style=\"clear: both;\"><\/div>\n<div style=\"margin-right: 30px; float: left; width: 373px; text-align: right;\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-8365 colorbox-11739\" style=\"padding-top: 12px;\" alt=\"Building Protection Power Gel\" src=\"http:\/\/dinostorm.com\/wp-content\/uploads\/2014\/08\/powergel_building_protection.png\" width=\"100\" height=\"100\" srcset=\"https:\/\/dinostorm.com\/wp-content\/uploads\/2014\/08\/powergel_building_protection.png 100w, https:\/\/dinostorm.com\/wp-content\/uploads\/2014\/08\/powergel_building_protection-36x36.png 36w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><\/p>\n<h2 style=\"padding-top: 1px;\">Prote\u00e7\u00e3o de Edif\u00edcios<\/h2>\n<div>Reduz em 60% as perdas de suprimentos dos seus edif\u00edcios quando est\u00e3o sob ataque.<\/div>\n<\/div>\n<div style=\"margin-left: 30px; float: left; width: 373px; text-align: right;\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-8364 colorbox-11739\" style=\"padding-top: 12px;\" alt=\"Fast Recovery Power Gel\" src=\"http:\/\/dinostorm.com\/wp-content\/uploads\/2014\/08\/powergel_fast_recovery.png\" width=\"100\" height=\"100\" srcset=\"https:\/\/dinostorm.com\/wp-content\/uploads\/2014\/08\/powergel_fast_recovery.png 100w, https:\/\/dinostorm.com\/wp-content\/uploads\/2014\/08\/powergel_fast_recovery-36x36.png 36w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><\/p>\n<h2 style=\"padding-top: 1px;\">Recupera\u00e7\u00e3o r\u00e1pida<\/h2>\n<div>Reduz em 60% o tempo necess\u00e1rio para se recuperar depois de ser derrotado em combate.<\/div>\n<\/div>\n<div style=\"clear: both;\"><\/div>\n<div style=\"float: left; width: 373px; text-align: left;\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-8363 colorbox-11739\" style=\"padding-top: 12px;\" alt=\"Healthy Recovery Power Gel\" src=\"http:\/\/dinostorm.com\/wp-content\/uploads\/2014\/08\/powergel_healthy_recovery.png\" width=\"100\" height=\"100\" srcset=\"https:\/\/dinostorm.com\/wp-content\/uploads\/2014\/08\/powergel_healthy_recovery.png 100w, https:\/\/dinostorm.com\/wp-content\/uploads\/2014\/08\/powergel_healthy_recovery-36x36.png 36w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><\/p>\n<h2 style=\"padding-top: 1px;\">Recupera\u00e7\u00e3o de sa\u00fade<\/h2>\n<div>Recupera 50% da sua vida , ao usar esse kit de recupera\u00e7\u00e3o.<\/div>\n<\/div>\n<div style=\"clear: both;\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>N\u00f3s adicionamos uma maneira nova de aumentar as habilidades do seu Ranger: Abra a janela do seu Perfil e procure pelos novos &#8220;G\u00e9is de Poder&#8221;. Aumente e melhore as habilidades do Seu Ranger com G\u00e9is [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":8414,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[39],"tags":[],"class_list":["post-11739","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novidades"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aumente as habilidades do seu Ranger de uma maneira inovadora: Adquira G\u00e9is de Poder! - Dino Storm<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dinostorm.com\/pt-br\/aumente-as-habilidades-do-seu-ranger-de-uma-maneira-inovadora-adquira-geis-de-poder\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aumente as habilidades do seu Ranger de uma maneira inovadora: Adquira G\u00e9is de Poder! - Dino Storm\" \/>\n<meta property=\"og:description\" content=\"N\u00f3s adicionamos uma maneira nova de aumentar as habilidades do seu Ranger: Abra a janela do seu Perfil e procure pelos novos &#8220;G\u00e9is de Poder&#8221;. Aumente e melhore as habilidades do Seu Ranger com G\u00e9is [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dinostorm.com\/pt-br\/aumente-as-habilidades-do-seu-ranger-de-uma-maneira-inovadora-adquira-geis-de-poder\/\" \/>\n<meta property=\"og:site_name\" content=\"Dino Storm\" \/>\n<meta property=\"article:published_time\" content=\"2013-08-15T08:00:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dinostorm.com\/wp-content\/uploads\/2014\/08\/dino.storm_.power_.gels_.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"808\" \/>\n\t<meta property=\"og:image:height\" content=\"327\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alexandre Maia\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alexandre Maia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dinostorm.com\\\/pt-br\\\/aumente-as-habilidades-do-seu-ranger-de-uma-maneira-inovadora-adquira-geis-de-poder\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dinostorm.com\\\/pt-br\\\/aumente-as-habilidades-do-seu-ranger-de-uma-maneira-inovadora-adquira-geis-de-poder\\\/\"},\"author\":{\"name\":\"Alexandre Maia\",\"@id\":\"https:\\\/\\\/dinostorm.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/e95cdfcb946945943679f1c51632fcfd\"},\"headline\":\"Aumente as habilidades do seu Ranger de uma maneira inovadora: Adquira G\u00e9is de Poder!\",\"datePublished\":\"2013-08-15T08:00:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dinostorm.com\\\/pt-br\\\/aumente-as-habilidades-do-seu-ranger-de-uma-maneira-inovadora-adquira-geis-de-poder\\\/\"},\"wordCount\":241,\"image\":{\"@id\":\"https:\\\/\\\/dinostorm.com\\\/pt-br\\\/aumente-as-habilidades-do-seu-ranger-de-uma-maneira-inovadora-adquira-geis-de-poder\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dinostorm.com\\\/wp-content\\\/uploads\\\/2014\\\/08\\\/dino.storm_.power_.gels_.jpg\",\"articleSection\":[\"Novidades\"],\"inLanguage\":\"pt-br\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dinostorm.com\\\/pt-br\\\/aumente-as-habilidades-do-seu-ranger-de-uma-maneira-inovadora-adquira-geis-de-poder\\\/\",\"url\":\"https:\\\/\\\/dinostorm.com\\\/pt-br\\\/aumente-as-habilidades-do-seu-ranger-de-uma-maneira-inovadora-adquira-geis-de-poder\\\/\",\"name\":\"Aumente as habilidades do seu Ranger de uma maneira inovadora: Adquira G\u00e9is de Poder! - Dino Storm\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dinostorm.com\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dinostorm.com\\\/pt-br\\\/aumente-as-habilidades-do-seu-ranger-de-uma-maneira-inovadora-adquira-geis-de-poder\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dinostorm.com\\\/pt-br\\\/aumente-as-habilidades-do-seu-ranger-de-uma-maneira-inovadora-adquira-geis-de-poder\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dinostorm.com\\\/wp-content\\\/uploads\\\/2014\\\/08\\\/dino.storm_.power_.gels_.jpg\",\"datePublished\":\"2013-08-15T08:00:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dinostorm.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/e95cdfcb946945943679f1c51632fcfd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dinostorm.com\\\/pt-br\\\/aumente-as-habilidades-do-seu-ranger-de-uma-maneira-inovadora-adquira-geis-de-poder\\\/#breadcrumb\"},\"inLanguage\":\"pt-br\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dinostorm.com\\\/pt-br\\\/aumente-as-habilidades-do-seu-ranger-de-uma-maneira-inovadora-adquira-geis-de-poder\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-br\",\"@id\":\"https:\\\/\\\/dinostorm.com\\\/pt-br\\\/aumente-as-habilidades-do-seu-ranger-de-uma-maneira-inovadora-adquira-geis-de-poder\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dinostorm.com\\\/wp-content\\\/uploads\\\/2014\\\/08\\\/dino.storm_.power_.gels_.jpg\",\"contentUrl\":\"https:\\\/\\\/dinostorm.com\\\/wp-content\\\/uploads\\\/2014\\\/08\\\/dino.storm_.power_.gels_.jpg\",\"width\":808,\"height\":327,\"caption\":\"Dino Storm \u2013 Power Gels\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dinostorm.com\\\/pt-br\\\/aumente-as-habilidades-do-seu-ranger-de-uma-maneira-inovadora-adquira-geis-de-poder\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dinostorm.com\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aumente as habilidades do seu Ranger de uma maneira inovadora: Adquira G\u00e9is de Poder!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dinostorm.com\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/dinostorm.com\\\/pt-br\\\/\",\"name\":\"Dino Storm\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dinostorm.com\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-br\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dinostorm.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/e95cdfcb946945943679f1c51632fcfd\",\"name\":\"Alexandre Maia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-br\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ea2563be3235f7f91ee620bf5ce2037cbf7d378034d005466d7f43ca72739ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ea2563be3235f7f91ee620bf5ce2037cbf7d378034d005466d7f43ca72739ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ea2563be3235f7f91ee620bf5ce2037cbf7d378034d005466d7f43ca72739ce?s=96&d=mm&r=g\",\"caption\":\"Alexandre Maia\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aumente as habilidades do seu Ranger de uma maneira inovadora: Adquira G\u00e9is de Poder! - Dino Storm","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dinostorm.com\/pt-br\/aumente-as-habilidades-do-seu-ranger-de-uma-maneira-inovadora-adquira-geis-de-poder\/","og_locale":"pt_PT","og_type":"article","og_title":"Aumente as habilidades do seu Ranger de uma maneira inovadora: Adquira G\u00e9is de Poder! - Dino Storm","og_description":"N\u00f3s adicionamos uma maneira nova de aumentar as habilidades do seu Ranger: Abra a janela do seu Perfil e procure pelos novos &#8220;G\u00e9is de Poder&#8221;. Aumente e melhore as habilidades do Seu Ranger com G\u00e9is [&hellip;]","og_url":"https:\/\/dinostorm.com\/pt-br\/aumente-as-habilidades-do-seu-ranger-de-uma-maneira-inovadora-adquira-geis-de-poder\/","og_site_name":"Dino Storm","article_published_time":"2013-08-15T08:00:13+00:00","og_image":[{"width":808,"height":327,"url":"https:\/\/dinostorm.com\/wp-content\/uploads\/2014\/08\/dino.storm_.power_.gels_.jpg","type":"image\/jpeg"}],"author":"Alexandre Maia","twitter_misc":{"Written by":"Alexandre Maia","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dinostorm.com\/pt-br\/aumente-as-habilidades-do-seu-ranger-de-uma-maneira-inovadora-adquira-geis-de-poder\/#article","isPartOf":{"@id":"https:\/\/dinostorm.com\/pt-br\/aumente-as-habilidades-do-seu-ranger-de-uma-maneira-inovadora-adquira-geis-de-poder\/"},"author":{"name":"Alexandre Maia","@id":"https:\/\/dinostorm.com\/pt-br\/#\/schema\/person\/e95cdfcb946945943679f1c51632fcfd"},"headline":"Aumente as habilidades do seu Ranger de uma maneira inovadora: Adquira G\u00e9is de Poder!","datePublished":"2013-08-15T08:00:13+00:00","mainEntityOfPage":{"@id":"https:\/\/dinostorm.com\/pt-br\/aumente-as-habilidades-do-seu-ranger-de-uma-maneira-inovadora-adquira-geis-de-poder\/"},"wordCount":241,"image":{"@id":"https:\/\/dinostorm.com\/pt-br\/aumente-as-habilidades-do-seu-ranger-de-uma-maneira-inovadora-adquira-geis-de-poder\/#primaryimage"},"thumbnailUrl":"https:\/\/dinostorm.com\/wp-content\/uploads\/2014\/08\/dino.storm_.power_.gels_.jpg","articleSection":["Novidades"],"inLanguage":"pt-br"},{"@type":"WebPage","@id":"https:\/\/dinostorm.com\/pt-br\/aumente-as-habilidades-do-seu-ranger-de-uma-maneira-inovadora-adquira-geis-de-poder\/","url":"https:\/\/dinostorm.com\/pt-br\/aumente-as-habilidades-do-seu-ranger-de-uma-maneira-inovadora-adquira-geis-de-poder\/","name":"Aumente as habilidades do seu Ranger de uma maneira inovadora: Adquira G\u00e9is de Poder! - Dino Storm","isPartOf":{"@id":"https:\/\/dinostorm.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dinostorm.com\/pt-br\/aumente-as-habilidades-do-seu-ranger-de-uma-maneira-inovadora-adquira-geis-de-poder\/#primaryimage"},"image":{"@id":"https:\/\/dinostorm.com\/pt-br\/aumente-as-habilidades-do-seu-ranger-de-uma-maneira-inovadora-adquira-geis-de-poder\/#primaryimage"},"thumbnailUrl":"https:\/\/dinostorm.com\/wp-content\/uploads\/2014\/08\/dino.storm_.power_.gels_.jpg","datePublished":"2013-08-15T08:00:13+00:00","author":{"@id":"https:\/\/dinostorm.com\/pt-br\/#\/schema\/person\/e95cdfcb946945943679f1c51632fcfd"},"breadcrumb":{"@id":"https:\/\/dinostorm.com\/pt-br\/aumente-as-habilidades-do-seu-ranger-de-uma-maneira-inovadora-adquira-geis-de-poder\/#breadcrumb"},"inLanguage":"pt-br","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dinostorm.com\/pt-br\/aumente-as-habilidades-do-seu-ranger-de-uma-maneira-inovadora-adquira-geis-de-poder\/"]}]},{"@type":"ImageObject","inLanguage":"pt-br","@id":"https:\/\/dinostorm.com\/pt-br\/aumente-as-habilidades-do-seu-ranger-de-uma-maneira-inovadora-adquira-geis-de-poder\/#primaryimage","url":"https:\/\/dinostorm.com\/wp-content\/uploads\/2014\/08\/dino.storm_.power_.gels_.jpg","contentUrl":"https:\/\/dinostorm.com\/wp-content\/uploads\/2014\/08\/dino.storm_.power_.gels_.jpg","width":808,"height":327,"caption":"Dino Storm \u2013 Power Gels"},{"@type":"BreadcrumbList","@id":"https:\/\/dinostorm.com\/pt-br\/aumente-as-habilidades-do-seu-ranger-de-uma-maneira-inovadora-adquira-geis-de-poder\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dinostorm.com\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Aumente as habilidades do seu Ranger de uma maneira inovadora: Adquira G\u00e9is de Poder!"}]},{"@type":"WebSite","@id":"https:\/\/dinostorm.com\/pt-br\/#website","url":"https:\/\/dinostorm.com\/pt-br\/","name":"Dino Storm","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dinostorm.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-br"},{"@type":"Person","@id":"https:\/\/dinostorm.com\/pt-br\/#\/schema\/person\/e95cdfcb946945943679f1c51632fcfd","name":"Alexandre Maia","image":{"@type":"ImageObject","inLanguage":"pt-br","@id":"https:\/\/secure.gravatar.com\/avatar\/5ea2563be3235f7f91ee620bf5ce2037cbf7d378034d005466d7f43ca72739ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5ea2563be3235f7f91ee620bf5ce2037cbf7d378034d005466d7f43ca72739ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5ea2563be3235f7f91ee620bf5ce2037cbf7d378034d005466d7f43ca72739ce?s=96&d=mm&r=g","caption":"Alexandre Maia"}}]}},"_links":{"self":[{"href":"https:\/\/dinostorm.com\/pt-br\/wp-json\/wp\/v2\/posts\/11739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dinostorm.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dinostorm.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dinostorm.com\/pt-br\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/dinostorm.com\/pt-br\/wp-json\/wp\/v2\/comments?post=11739"}],"version-history":[{"count":0,"href":"https:\/\/dinostorm.com\/pt-br\/wp-json\/wp\/v2\/posts\/11739\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dinostorm.com\/pt-br\/wp-json\/wp\/v2\/media\/8414"}],"wp:attachment":[{"href":"https:\/\/dinostorm.com\/pt-br\/wp-json\/wp\/v2\/media?parent=11739"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dinostorm.com\/pt-br\/wp-json\/wp\/v2\/categories?post=11739"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dinostorm.com\/pt-br\/wp-json\/wp\/v2\/tags?post=11739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}