{"id":4172,"date":"2013-01-09T16:30:16","date_gmt":"2013-01-09T14:30:16","guid":{"rendered":"http:\/\/dinostorm.com\/dino-storm-is-celebrating-25000-likes-2"},"modified":"2018-02-01T14:25:03","modified_gmt":"2018-02-01T12:25:03","slug":"dino-storm-is-celebrating-25000-likes","status":"publish","type":"post","link":"https:\/\/dinostorm.com\/es\/dino-storm-is-celebrating-25000-likes\/","title":{"rendered":"Dino Storm est\u00e1 celebrando 25.000 Me Gusta"},"content":{"rendered":"<p>S\u00f3lo un mes y medio atr\u00e1s, el n\u00famero de Me Gusta para Dino Storm en Facebook hab\u00eda llegado a lo que llamamos una <a title=\"Dino Storm is Celebrating 10,000 Likes\" href=\"http:\/\/dinostorm.com\/es\/dino-storm-is-celebrating-10000-likes\" target=\"_blank\">&#8220;Nueva, alta magia&#8221;<\/a>.<br \/>\nHoy nos humill\u00f3 de nuevo a medida que han aumentado el n\u00famero a un incre\u00edble 25.000 Me Gusta \u2013 Muchas gracias, ustedes son incre\u00edbles!<\/p>\n<h1>\u00a1Vaya! \u2013 25.000 Me Gusta en Facebook! \u00a1Reclame su pintura de dinosaurio gratis ahora mismo!<\/h1>\n<p>Visite\u00a0<a href=\"https:\/\/www.facebook.com\/dinostorm\" target=\"_blank\">facebook.com\/dinostorm<\/a>\u00a0y busque su c\u00f3digo de pintura de dinosaurio gratis. Por favor, no se olvide de compartir en Facebook para que sus amigos puedan beneficiarse tambi\u00e9n de \u00e9l!<\/p>\n<h4>Como introducir su c\u00f3digo de pintura de dinosaurio gratis en Dino Storm:<\/h4>\n<ol>\n<li>Haga clic en el bot\u00f3n &#8220;Configuraci\u00f3n&#8221; en la esquina superior derecha.<\/li>\n<li>Elija la segunda opci\u00f3n &#8220;C\u00f3digos de promoci\u00f3n&#8221;.<\/li>\n<li>Ingrese su c\u00f3digo de regalo y pulsa el bot\u00f3n &#8220;Desbloquear&#8221;. \u00a1Eso es!<\/li>\n<\/ol>\n<h3>\u00a1Disfrute de la nueva apariencia de su dinosaurio!<\/h3>\n<p>\u2013 Su Equipo de Splitscreen Games<\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00f3lo un mes y medio atr\u00e1s, el n\u00famero de Me Gusta para Dino Storm en Facebook hab\u00eda llegado a lo que llamamos una &#8220;Nueva, alta magia&#8221;. Hoy nos humill\u00f3 de nuevo a medida que han [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":4155,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[14],"tags":[],"class_list":["post-4172","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dino Storm est\u00e1 celebrando 25.000 Me Gusta<\/title>\n<meta name=\"description\" content=\"Hoy nos humill\u00f3 de nuevo a medida que han aumentado el n\u00famero a un incre\u00edble 25.000 Me Gusta \u2013 Muchas gracias, ustedes son incre\u00edbles!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dinostorm.com\/es\/dino-storm-is-celebrating-25000-likes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dino Storm est\u00e1 celebrando 25.000 Me Gusta\" \/>\n<meta property=\"og:description\" content=\"Hoy nos humill\u00f3 de nuevo a medida que han aumentado el n\u00famero a un incre\u00edble 25.000 Me Gusta \u2013 Muchas gracias, ustedes son incre\u00edbles!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dinostorm.com\/es\/dino-storm-is-celebrating-25000-likes\/\" \/>\n<meta property=\"og:site_name\" content=\"DinoStorm\" \/>\n<meta property=\"article:published_time\" content=\"2013-01-09T14:30:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-02-01T12:25:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dinostorm.com\/wp-content\/uploads\/2014\/01\/dino.storm_.25k.likes_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"808\" \/>\n\t<meta property=\"og:image:height\" content=\"327\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alexandre Maia\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alexandre Maia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/dino-storm-is-celebrating-25000-likes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/dino-storm-is-celebrating-25000-likes\\\/\"},\"author\":{\"name\":\"Alexandre Maia\",\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/#\\\/schema\\\/person\\\/e95cdfcb946945943679f1c51632fcfd\"},\"headline\":\"Dino Storm est\u00e1 celebrando 25.000 Me Gusta\",\"datePublished\":\"2013-01-09T14:30:16+00:00\",\"dateModified\":\"2018-02-01T12:25:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/dino-storm-is-celebrating-25000-likes\\\/\"},\"wordCount\":170,\"image\":{\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/dino-storm-is-celebrating-25000-likes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dinostorm.com\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/dino.storm_.25k.likes_1.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/dino-storm-is-celebrating-25000-likes\\\/\",\"url\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/dino-storm-is-celebrating-25000-likes\\\/\",\"name\":\"Dino Storm est\u00e1 celebrando 25.000 Me Gusta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/dino-storm-is-celebrating-25000-likes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/dino-storm-is-celebrating-25000-likes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dinostorm.com\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/dino.storm_.25k.likes_1.jpg\",\"datePublished\":\"2013-01-09T14:30:16+00:00\",\"dateModified\":\"2018-02-01T12:25:03+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/#\\\/schema\\\/person\\\/e95cdfcb946945943679f1c51632fcfd\"},\"description\":\"Hoy nos humill\u00f3 de nuevo a medida que han aumentado el n\u00famero a un incre\u00edble 25.000 Me Gusta \u2013 Muchas gracias, ustedes son incre\u00edbles!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/dino-storm-is-celebrating-25000-likes\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dinostorm.com\\\/es\\\/dino-storm-is-celebrating-25000-likes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/dino-storm-is-celebrating-25000-likes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dinostorm.com\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/dino.storm_.25k.likes_1.jpg\",\"contentUrl\":\"https:\\\/\\\/dinostorm.com\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/dino.storm_.25k.likes_1.jpg\",\"width\":808,\"height\":327,\"caption\":\"Dino Storm \u2013 25,000 Likes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/dino-storm-is-celebrating-25000-likes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dino Storm est\u00e1 celebrando 25.000 Me Gusta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/\",\"name\":\"DinoStorm\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/#\\\/schema\\\/person\\\/e95cdfcb946945943679f1c51632fcfd\",\"name\":\"Alexandre Maia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ea2563be3235f7f91ee620bf5ce2037cbf7d378034d005466d7f43ca72739ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ea2563be3235f7f91ee620bf5ce2037cbf7d378034d005466d7f43ca72739ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ea2563be3235f7f91ee620bf5ce2037cbf7d378034d005466d7f43ca72739ce?s=96&d=mm&r=g\",\"caption\":\"Alexandre Maia\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dino Storm est\u00e1 celebrando 25.000 Me Gusta","description":"Hoy nos humill\u00f3 de nuevo a medida que han aumentado el n\u00famero a un incre\u00edble 25.000 Me Gusta \u2013 Muchas gracias, ustedes son incre\u00edbles!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dinostorm.com\/es\/dino-storm-is-celebrating-25000-likes\/","og_locale":"es_ES","og_type":"article","og_title":"Dino Storm est\u00e1 celebrando 25.000 Me Gusta","og_description":"Hoy nos humill\u00f3 de nuevo a medida que han aumentado el n\u00famero a un incre\u00edble 25.000 Me Gusta \u2013 Muchas gracias, ustedes son incre\u00edbles!","og_url":"https:\/\/dinostorm.com\/es\/dino-storm-is-celebrating-25000-likes\/","og_site_name":"DinoStorm","article_published_time":"2013-01-09T14:30:16+00:00","article_modified_time":"2018-02-01T12:25:03+00:00","og_image":[{"width":808,"height":327,"url":"https:\/\/dinostorm.com\/wp-content\/uploads\/2014\/01\/dino.storm_.25k.likes_1.jpg","type":"image\/jpeg"}],"author":"Alexandre Maia","twitter_misc":{"Escrito por":"Alexandre Maia","Tiempo de lectura":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dinostorm.com\/es\/dino-storm-is-celebrating-25000-likes\/#article","isPartOf":{"@id":"https:\/\/dinostorm.com\/es\/dino-storm-is-celebrating-25000-likes\/"},"author":{"name":"Alexandre Maia","@id":"https:\/\/dinostorm.com\/es\/#\/schema\/person\/e95cdfcb946945943679f1c51632fcfd"},"headline":"Dino Storm est\u00e1 celebrando 25.000 Me Gusta","datePublished":"2013-01-09T14:30:16+00:00","dateModified":"2018-02-01T12:25:03+00:00","mainEntityOfPage":{"@id":"https:\/\/dinostorm.com\/es\/dino-storm-is-celebrating-25000-likes\/"},"wordCount":170,"image":{"@id":"https:\/\/dinostorm.com\/es\/dino-storm-is-celebrating-25000-likes\/#primaryimage"},"thumbnailUrl":"https:\/\/dinostorm.com\/wp-content\/uploads\/2014\/01\/dino.storm_.25k.likes_1.jpg","articleSection":["Noticias"],"inLanguage":"es-ES"},{"@type":"WebPage","@id":"https:\/\/dinostorm.com\/es\/dino-storm-is-celebrating-25000-likes\/","url":"https:\/\/dinostorm.com\/es\/dino-storm-is-celebrating-25000-likes\/","name":"Dino Storm est\u00e1 celebrando 25.000 Me Gusta","isPartOf":{"@id":"https:\/\/dinostorm.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dinostorm.com\/es\/dino-storm-is-celebrating-25000-likes\/#primaryimage"},"image":{"@id":"https:\/\/dinostorm.com\/es\/dino-storm-is-celebrating-25000-likes\/#primaryimage"},"thumbnailUrl":"https:\/\/dinostorm.com\/wp-content\/uploads\/2014\/01\/dino.storm_.25k.likes_1.jpg","datePublished":"2013-01-09T14:30:16+00:00","dateModified":"2018-02-01T12:25:03+00:00","author":{"@id":"https:\/\/dinostorm.com\/es\/#\/schema\/person\/e95cdfcb946945943679f1c51632fcfd"},"description":"Hoy nos humill\u00f3 de nuevo a medida que han aumentado el n\u00famero a un incre\u00edble 25.000 Me Gusta \u2013 Muchas gracias, ustedes son incre\u00edbles!","breadcrumb":{"@id":"https:\/\/dinostorm.com\/es\/dino-storm-is-celebrating-25000-likes\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dinostorm.com\/es\/dino-storm-is-celebrating-25000-likes\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/dinostorm.com\/es\/dino-storm-is-celebrating-25000-likes\/#primaryimage","url":"https:\/\/dinostorm.com\/wp-content\/uploads\/2014\/01\/dino.storm_.25k.likes_1.jpg","contentUrl":"https:\/\/dinostorm.com\/wp-content\/uploads\/2014\/01\/dino.storm_.25k.likes_1.jpg","width":808,"height":327,"caption":"Dino Storm \u2013 25,000 Likes"},{"@type":"BreadcrumbList","@id":"https:\/\/dinostorm.com\/es\/dino-storm-is-celebrating-25000-likes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dinostorm.com\/es\/"},{"@type":"ListItem","position":2,"name":"Dino Storm est\u00e1 celebrando 25.000 Me Gusta"}]},{"@type":"WebSite","@id":"https:\/\/dinostorm.com\/es\/#website","url":"https:\/\/dinostorm.com\/es\/","name":"DinoStorm","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dinostorm.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/dinostorm.com\/es\/#\/schema\/person\/e95cdfcb946945943679f1c51632fcfd","name":"Alexandre Maia","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/5ea2563be3235f7f91ee620bf5ce2037cbf7d378034d005466d7f43ca72739ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5ea2563be3235f7f91ee620bf5ce2037cbf7d378034d005466d7f43ca72739ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5ea2563be3235f7f91ee620bf5ce2037cbf7d378034d005466d7f43ca72739ce?s=96&d=mm&r=g","caption":"Alexandre Maia"}}]}},"_links":{"self":[{"href":"https:\/\/dinostorm.com\/es\/wp-json\/wp\/v2\/posts\/4172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dinostorm.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dinostorm.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dinostorm.com\/es\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/dinostorm.com\/es\/wp-json\/wp\/v2\/comments?post=4172"}],"version-history":[{"count":0,"href":"https:\/\/dinostorm.com\/es\/wp-json\/wp\/v2\/posts\/4172\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dinostorm.com\/es\/wp-json\/wp\/v2\/media\/4155"}],"wp:attachment":[{"href":"https:\/\/dinostorm.com\/es\/wp-json\/wp\/v2\/media?parent=4172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dinostorm.com\/es\/wp-json\/wp\/v2\/categories?post=4172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dinostorm.com\/es\/wp-json\/wp\/v2\/tags?post=4172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}