{"id":27823,"date":"2019-10-14T17:52:45","date_gmt":"2019-10-14T15:52:45","guid":{"rendered":"https:\/\/forum.dinostorm.com\/threads\/american-asian-servers-priority-maintenance-on-october-15-2019.17969\/"},"modified":"2019-10-14T17:52:45","modified_gmt":"2019-10-14T15:52:45","slug":"american-asian-servers-priority-maintenance-on-october-15-2019","status":"publish","type":"post","link":"https:\/\/dinostorm.com\/es\/american-asian-servers-priority-maintenance-on-october-15-2019\/","title":{"rendered":"[American\/Asian servers] Priority maintenance on October 15, 2019"},"content":{"rendered":"<div class=\"bbWrapper\">\n<div class=\"lbContainer lbContainer--inline \" title=\"\"\n\t\tdata-xf-init=\"lightbox\"\n\t\tdata-lb-single-image=\"1\"\n\t\tdata-lb-container-zoom=\"1\"\n\t\tdata-lb-trigger=\".js-lbImage-_xfUid-49-1588146315\"\n\t\tdata-lb-id=\"_xfUid-49-1588146315\"><\/p>\n<div class=\"lbContainer-zoomer js-lbImage-_xfUid-49-1588146315\" data-src=\"https:\/\/splitscreen-games.com\/content\/games\/ds_server_maintenance.jpg\" aria-label=\"Zoom\"><\/div>\n<p>\t\t<img decoding=\"async\" src=\"https:\/\/splitscreen-games.com\/content\/games\/ds_server_maintenance.jpg\" data-url=\"https:\/\/splitscreen-games.com\/content\/games\/ds_server_maintenance.jpg\" class=\"bbImage colorbox-27823\" data-zoom-  style=\"\" \/>\n\t<\/div>\n<p><b><span style=\"font-size: 18px\"><span style=\"color: #00BFBF\">[American\/Asian servers] Priority maintenance on October 15, 2019<\/span><\/span><\/b><\/p>\n<p>Around <b><span style=\"color: #00BFBF\">05:00 (5 AM) server time<\/span><\/b>, our American and Asian game servers America_1-5 and Asia_1 will shut down for up to <b><span style=\"color: #00BFBF\">2 hours<\/span><\/b> of maintenance work to be carried out.<\/p>\n<p><a href=\"https:\/\/support.splitscreenstudios.com\/index.php?\/News\/NewsItem\/View\/118\/americanasian-servers-up-to-2-hours-of-priority-server-maintenance-starting-5-am-utc-4\"  class=\"link link--external\" rel=\"nofollow noopener\">Read more<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>[American\/Asian servers] Priority maintenance on October 15, 2019 Around 05:00 (5 AM) server time, our American and Asian game servers America_1-5 and Asia_1 will shut down for up to 2 hours of maintenance work to [&hellip;]<\/p>\n","protected":false},"author":28,"featured_media":15052,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[7],"tags":[],"class_list":["post-27823","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>[American\/Asian servers] Priority maintenance on October 15, 2019 - DinoStorm<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dinostorm.com\/es\/american-asian-servers-priority-maintenance-on-october-15-2019\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[American\/Asian servers] Priority maintenance on October 15, 2019 - DinoStorm\" \/>\n<meta property=\"og:description\" content=\"[American\/Asian servers] Priority maintenance on October 15, 2019 Around 05:00 (5 AM) server time, our American and Asian game servers America_1-5 and Asia_1 will shut down for up to 2 hours of maintenance work to [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dinostorm.com\/es\/american-asian-servers-priority-maintenance-on-october-15-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"DinoStorm\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-14T15:52:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dinostorm.com\/wp-content\/uploads\/2012\/09\/ds_jungle_01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ForumMaster\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ForumMaster\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/american-asian-servers-priority-maintenance-on-october-15-2019\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/american-asian-servers-priority-maintenance-on-october-15-2019\\\/\"},\"author\":{\"name\":\"ForumMaster\",\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/#\\\/schema\\\/person\\\/fbc70a222ff75e4daa6ff575624b8ba5\"},\"headline\":\"[American\\\/Asian servers] Priority maintenance on October 15, 2019\",\"datePublished\":\"2019-10-14T15:52:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/american-asian-servers-priority-maintenance-on-october-15-2019\\\/\"},\"wordCount\":44,\"image\":{\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/american-asian-servers-priority-maintenance-on-october-15-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dinostorm.com\\\/wp-content\\\/uploads\\\/2012\\\/09\\\/ds_jungle_01.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"es-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/american-asian-servers-priority-maintenance-on-october-15-2019\\\/\",\"url\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/american-asian-servers-priority-maintenance-on-october-15-2019\\\/\",\"name\":\"[American\\\/Asian servers] Priority maintenance on October 15, 2019 - DinoStorm\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/american-asian-servers-priority-maintenance-on-october-15-2019\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/american-asian-servers-priority-maintenance-on-october-15-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dinostorm.com\\\/wp-content\\\/uploads\\\/2012\\\/09\\\/ds_jungle_01.jpg\",\"datePublished\":\"2019-10-14T15:52:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/#\\\/schema\\\/person\\\/fbc70a222ff75e4daa6ff575624b8ba5\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/american-asian-servers-priority-maintenance-on-october-15-2019\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dinostorm.com\\\/es\\\/american-asian-servers-priority-maintenance-on-october-15-2019\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/american-asian-servers-priority-maintenance-on-october-15-2019\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dinostorm.com\\\/wp-content\\\/uploads\\\/2012\\\/09\\\/ds_jungle_01.jpg\",\"contentUrl\":\"https:\\\/\\\/dinostorm.com\\\/wp-content\\\/uploads\\\/2012\\\/09\\\/ds_jungle_01.jpg\",\"width\":1280,\"height\":720,\"caption\":\"Beware of dangerous bandits in Mokon Woods are everywhere.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/american-asian-servers-priority-maintenance-on-october-15-2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[American\\\/Asian servers] Priority maintenance on October 15, 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/\",\"name\":\"DinoStorm\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/#\\\/schema\\\/person\\\/fbc70a222ff75e4daa6ff575624b8ba5\",\"name\":\"ForumMaster\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d9beb1bb73cc52d88efb4aa17aa177f1512b4ffb7ef431d9294d69a3804cd29?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d9beb1bb73cc52d88efb4aa17aa177f1512b4ffb7ef431d9294d69a3804cd29?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d9beb1bb73cc52d88efb4aa17aa177f1512b4ffb7ef431d9294d69a3804cd29?s=96&d=mm&r=g\",\"caption\":\"ForumMaster\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[American\/Asian servers] Priority maintenance on October 15, 2019 - DinoStorm","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dinostorm.com\/es\/american-asian-servers-priority-maintenance-on-october-15-2019\/","og_locale":"es_ES","og_type":"article","og_title":"[American\/Asian servers] Priority maintenance on October 15, 2019 - DinoStorm","og_description":"[American\/Asian servers] Priority maintenance on October 15, 2019 Around 05:00 (5 AM) server time, our American and Asian game servers America_1-5 and Asia_1 will shut down for up to 2 hours of maintenance work to [&hellip;]","og_url":"https:\/\/dinostorm.com\/es\/american-asian-servers-priority-maintenance-on-october-15-2019\/","og_site_name":"DinoStorm","article_published_time":"2019-10-14T15:52:45+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/dinostorm.com\/wp-content\/uploads\/2012\/09\/ds_jungle_01.jpg","type":"image\/jpeg"}],"author":"ForumMaster","twitter_misc":{"Escrito por":"ForumMaster"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dinostorm.com\/es\/american-asian-servers-priority-maintenance-on-october-15-2019\/#article","isPartOf":{"@id":"https:\/\/dinostorm.com\/es\/american-asian-servers-priority-maintenance-on-october-15-2019\/"},"author":{"name":"ForumMaster","@id":"https:\/\/dinostorm.com\/es\/#\/schema\/person\/fbc70a222ff75e4daa6ff575624b8ba5"},"headline":"[American\/Asian servers] Priority maintenance on October 15, 2019","datePublished":"2019-10-14T15:52:45+00:00","mainEntityOfPage":{"@id":"https:\/\/dinostorm.com\/es\/american-asian-servers-priority-maintenance-on-october-15-2019\/"},"wordCount":44,"image":{"@id":"https:\/\/dinostorm.com\/es\/american-asian-servers-priority-maintenance-on-october-15-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/dinostorm.com\/wp-content\/uploads\/2012\/09\/ds_jungle_01.jpg","articleSection":["News"],"inLanguage":"es-ES"},{"@type":"WebPage","@id":"https:\/\/dinostorm.com\/es\/american-asian-servers-priority-maintenance-on-october-15-2019\/","url":"https:\/\/dinostorm.com\/es\/american-asian-servers-priority-maintenance-on-october-15-2019\/","name":"[American\/Asian servers] Priority maintenance on October 15, 2019 - DinoStorm","isPartOf":{"@id":"https:\/\/dinostorm.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dinostorm.com\/es\/american-asian-servers-priority-maintenance-on-october-15-2019\/#primaryimage"},"image":{"@id":"https:\/\/dinostorm.com\/es\/american-asian-servers-priority-maintenance-on-october-15-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/dinostorm.com\/wp-content\/uploads\/2012\/09\/ds_jungle_01.jpg","datePublished":"2019-10-14T15:52:45+00:00","author":{"@id":"https:\/\/dinostorm.com\/es\/#\/schema\/person\/fbc70a222ff75e4daa6ff575624b8ba5"},"breadcrumb":{"@id":"https:\/\/dinostorm.com\/es\/american-asian-servers-priority-maintenance-on-october-15-2019\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dinostorm.com\/es\/american-asian-servers-priority-maintenance-on-october-15-2019\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/dinostorm.com\/es\/american-asian-servers-priority-maintenance-on-october-15-2019\/#primaryimage","url":"https:\/\/dinostorm.com\/wp-content\/uploads\/2012\/09\/ds_jungle_01.jpg","contentUrl":"https:\/\/dinostorm.com\/wp-content\/uploads\/2012\/09\/ds_jungle_01.jpg","width":1280,"height":720,"caption":"Beware of dangerous bandits in Mokon Woods are everywhere."},{"@type":"BreadcrumbList","@id":"https:\/\/dinostorm.com\/es\/american-asian-servers-priority-maintenance-on-october-15-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dinostorm.com\/es\/"},{"@type":"ListItem","position":2,"name":"[American\/Asian servers] Priority maintenance on October 15, 2019"}]},{"@type":"WebSite","@id":"https:\/\/dinostorm.com\/es\/#website","url":"https:\/\/dinostorm.com\/es\/","name":"DinoStorm","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dinostorm.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/dinostorm.com\/es\/#\/schema\/person\/fbc70a222ff75e4daa6ff575624b8ba5","name":"ForumMaster","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/2d9beb1bb73cc52d88efb4aa17aa177f1512b4ffb7ef431d9294d69a3804cd29?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2d9beb1bb73cc52d88efb4aa17aa177f1512b4ffb7ef431d9294d69a3804cd29?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2d9beb1bb73cc52d88efb4aa17aa177f1512b4ffb7ef431d9294d69a3804cd29?s=96&d=mm&r=g","caption":"ForumMaster"}}]}},"_links":{"self":[{"href":"https:\/\/dinostorm.com\/es\/wp-json\/wp\/v2\/posts\/27823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dinostorm.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dinostorm.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dinostorm.com\/es\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/dinostorm.com\/es\/wp-json\/wp\/v2\/comments?post=27823"}],"version-history":[{"count":181,"href":"https:\/\/dinostorm.com\/es\/wp-json\/wp\/v2\/posts\/27823\/revisions"}],"predecessor-version":[{"id":32719,"href":"https:\/\/dinostorm.com\/es\/wp-json\/wp\/v2\/posts\/27823\/revisions\/32719"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dinostorm.com\/es\/wp-json\/wp\/v2\/media\/15052"}],"wp:attachment":[{"href":"https:\/\/dinostorm.com\/es\/wp-json\/wp\/v2\/media?parent=27823"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dinostorm.com\/es\/wp-json\/wp\/v2\/categories?post=27823"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dinostorm.com\/es\/wp-json\/wp\/v2\/tags?post=27823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}