{"id":11032,"date":"2014-06-12T17:00:58","date_gmt":"2014-06-12T15:00:58","guid":{"rendered":"http:\/\/dinostorm.com\/the-dinoball-challenge-collect-32-brand-new-sets-of-clothes-2"},"modified":"2014-06-12T17:52:13","modified_gmt":"2014-06-12T15:52:13","slug":"el-desafio-dinoball-consigue-32-conjuntos-de-ropa-completamente-nuevos","status":"publish","type":"post","link":"https:\/\/dinostorm.com\/es\/el-desafio-dinoball-consigue-32-conjuntos-de-ropa-completamente-nuevos\/","title":{"rendered":"El desaf\u00edo Dinoball \u2013 consigue 32 conjuntos de ropa completamente nuevos!"},"content":{"rendered":"<div>Dinoball consiste en trabajo en equipo \u00a1Sigue las misiones del evento y pasa las bolas a otros jugadores para tener en tus manos un fant\u00e1stico conjunto de ropa para utilizar en la triforja! Recoja todos los 32 conjuntos:\u00a0<a title=\"List of Items to complete achievement sets\" href=\"http:\/\/forum.dinostorm.com\/viewtopic.php?f=83&amp;t=8976#p24822\" target=\"_blank\">http:\/\/forum.dinostorm.com\/viewtopic.php?f=83&amp;t=8976#p24822<\/a><\/div>\n<div style=\"margin-right: 20px; float: left; width: 118px; text-align: left;\">\n<h5 style=\"margin-bottom: 2px;\">1. Derrota a los dinosaurios monstruosos<\/h5>\n<div>Sigue las misiones del evento para conseguir cajas de recompensa.<\/div>\n<\/div>\n<div style=\"margin-right: 20px; float: left; width: 118px; text-align: left;\">\n<h5 style=\"margin-bottom: 2px;\">2. Abre las recompensas con llaves<\/h5>\n<div>Las Cajas de recompensa solo puede abrirse con llaves. Visita a los promotores de Dinoball para conseguir llaves de cajas de recomensa.<\/div>\n<\/div>\n<div style=\"margin-right: 20px; float: left; width: 118px; text-align: left;\">\n<h5 style=\"margin-bottom: 2px;\">3. Recoge pelotas<\/h5>\n<div>Las pelotas de f\u00fatbol aparecen en cualquier sitio. Rec\u00f3gelas y p\u00e1saslas a otros jugadores.<\/div>\n<\/div>\n<div style=\"margin-right: 20px; float: left; width: 118px; text-align: left;\">\n<h5 style=\"margin-bottom: 2px;\">4. Pasa la pelota<\/h5>\n<div>Pasa las pelotas a otros jugadores para recibir Esp\u00edritu de equipo.<\/div>\n<\/div>\n<div style=\"margin-right: 20px; float: left; width: 118px; text-align: left;\">\n<h5 style=\"margin-bottom: 2px;\">5. Intercambia Esp\u00edritu de equipo<\/h5>\n<div>Intercambia Esp\u00edritu de Equipo por llaves de cajas de recompensa a trav\u00e9s de los promotores de Dinoball.<\/div>\n<\/div>\n<div style=\"float: left; width: 118px; text-align: left;\">\n<h5 style=\"margin-bottom: 2px;\">6. Las llaves abrir\u00e1n las cajas de recompensa<\/h5>\n<div>Necesitas tener llaves en tu inventario para abrir las cajas de recompensa. Los promotores de Dinoball te cambiar\u00e1n llaves por Esp\u00edritu de equipo.<\/div>\n<\/div>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-11023 colorbox-11032\" alt=\"dino.storm.dinoball.howto\" src=\"http:\/\/dinostorm.com\/wp-content\/uploads\/2015\/06\/dino.storm_.dinoball.howto_.png\" width=\"709\" height=\"310\" srcset=\"https:\/\/dinostorm.com\/wp-content\/uploads\/2015\/06\/dino.storm_.dinoball.howto_.png 709w, https:\/\/dinostorm.com\/wp-content\/uploads\/2015\/06\/dino.storm_.dinoball.howto_-300x131.png 300w\" sizes=\"auto, (max-width: 709px) 100vw, 709px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dinoball consiste en trabajo en equipo \u00a1Sigue las misiones del evento y pasa las bolas a otros jugadores para tener en tus manos un fant\u00e1stico conjunto de ropa para utilizar en la triforja! Recoja todos [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":11048,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[14],"tags":[],"class_list":["post-11032","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El desaf\u00edo Dinoball \u2013 consigue 32 conjuntos de ropa completamente nuevos! - DinoStorm<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dinostorm.com\/es\/el-desafio-dinoball-consigue-32-conjuntos-de-ropa-completamente-nuevos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El desaf\u00edo Dinoball \u2013 consigue 32 conjuntos de ropa completamente nuevos! - DinoStorm\" \/>\n<meta property=\"og:description\" content=\"Dinoball consiste en trabajo en equipo \u00a1Sigue las misiones del evento y pasa las bolas a otros jugadores para tener en tus manos un fant\u00e1stico conjunto de ropa para utilizar en la triforja! Recoja todos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dinostorm.com\/es\/el-desafio-dinoball-consigue-32-conjuntos-de-ropa-completamente-nuevos\/\" \/>\n<meta property=\"og:site_name\" content=\"DinoStorm\" \/>\n<meta property=\"article:published_time\" content=\"2014-06-12T15:00:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-06-12T15:52:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dinostorm.com\/wp-content\/uploads\/2014\/06\/dino.storm_.dinoball.teaser.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"808\" \/>\n\t<meta property=\"og:image:height\" content=\"327\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"jgeisler\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"jgeisler\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/el-desafio-dinoball-consigue-32-conjuntos-de-ropa-completamente-nuevos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/el-desafio-dinoball-consigue-32-conjuntos-de-ropa-completamente-nuevos\\\/\"},\"author\":{\"name\":\"jgeisler\",\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/#\\\/schema\\\/person\\\/99830ffffdd9f24640cefba5d01b851b\"},\"headline\":\"El desaf\u00edo Dinoball \u2013 consigue 32 conjuntos de ropa completamente nuevos!\",\"datePublished\":\"2014-06-12T15:00:58+00:00\",\"dateModified\":\"2014-06-12T15:52:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/el-desafio-dinoball-consigue-32-conjuntos-de-ropa-completamente-nuevos\\\/\"},\"wordCount\":191,\"image\":{\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/el-desafio-dinoball-consigue-32-conjuntos-de-ropa-completamente-nuevos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dinostorm.com\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/dino.storm_.dinoball.teaser.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/el-desafio-dinoball-consigue-32-conjuntos-de-ropa-completamente-nuevos\\\/\",\"url\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/el-desafio-dinoball-consigue-32-conjuntos-de-ropa-completamente-nuevos\\\/\",\"name\":\"El desaf\u00edo Dinoball \u2013 consigue 32 conjuntos de ropa completamente nuevos! - DinoStorm\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/el-desafio-dinoball-consigue-32-conjuntos-de-ropa-completamente-nuevos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/el-desafio-dinoball-consigue-32-conjuntos-de-ropa-completamente-nuevos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dinostorm.com\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/dino.storm_.dinoball.teaser.jpg\",\"datePublished\":\"2014-06-12T15:00:58+00:00\",\"dateModified\":\"2014-06-12T15:52:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/#\\\/schema\\\/person\\\/99830ffffdd9f24640cefba5d01b851b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/el-desafio-dinoball-consigue-32-conjuntos-de-ropa-completamente-nuevos\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dinostorm.com\\\/es\\\/el-desafio-dinoball-consigue-32-conjuntos-de-ropa-completamente-nuevos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/el-desafio-dinoball-consigue-32-conjuntos-de-ropa-completamente-nuevos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dinostorm.com\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/dino.storm_.dinoball.teaser.jpg\",\"contentUrl\":\"https:\\\/\\\/dinostorm.com\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/dino.storm_.dinoball.teaser.jpg\",\"width\":808,\"height\":327,\"caption\":\"Dino Storm \u2013 Dinoball 2014\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/el-desafio-dinoball-consigue-32-conjuntos-de-ropa-completamente-nuevos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El desaf\u00edo Dinoball \u2013 consigue 32 conjuntos de ropa completamente nuevos!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/\",\"name\":\"DinoStorm\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/#\\\/schema\\\/person\\\/99830ffffdd9f24640cefba5d01b851b\",\"name\":\"jgeisler\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c0d594e25fb116f72f06928d933d61ec76d18cc8ffa842a02afec16ad0940be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c0d594e25fb116f72f06928d933d61ec76d18cc8ffa842a02afec16ad0940be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c0d594e25fb116f72f06928d933d61ec76d18cc8ffa842a02afec16ad0940be?s=96&d=mm&r=g\",\"caption\":\"jgeisler\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El desaf\u00edo Dinoball \u2013 consigue 32 conjuntos de ropa completamente nuevos! - DinoStorm","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dinostorm.com\/es\/el-desafio-dinoball-consigue-32-conjuntos-de-ropa-completamente-nuevos\/","og_locale":"es_ES","og_type":"article","og_title":"El desaf\u00edo Dinoball \u2013 consigue 32 conjuntos de ropa completamente nuevos! - DinoStorm","og_description":"Dinoball consiste en trabajo en equipo \u00a1Sigue las misiones del evento y pasa las bolas a otros jugadores para tener en tus manos un fant\u00e1stico conjunto de ropa para utilizar en la triforja! Recoja todos [&hellip;]","og_url":"https:\/\/dinostorm.com\/es\/el-desafio-dinoball-consigue-32-conjuntos-de-ropa-completamente-nuevos\/","og_site_name":"DinoStorm","article_published_time":"2014-06-12T15:00:58+00:00","article_modified_time":"2014-06-12T15:52:13+00:00","og_image":[{"width":808,"height":327,"url":"https:\/\/dinostorm.com\/wp-content\/uploads\/2014\/06\/dino.storm_.dinoball.teaser.jpg","type":"image\/jpeg"}],"author":"jgeisler","twitter_misc":{"Escrito por":"jgeisler","Tiempo de lectura":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dinostorm.com\/es\/el-desafio-dinoball-consigue-32-conjuntos-de-ropa-completamente-nuevos\/#article","isPartOf":{"@id":"https:\/\/dinostorm.com\/es\/el-desafio-dinoball-consigue-32-conjuntos-de-ropa-completamente-nuevos\/"},"author":{"name":"jgeisler","@id":"https:\/\/dinostorm.com\/es\/#\/schema\/person\/99830ffffdd9f24640cefba5d01b851b"},"headline":"El desaf\u00edo Dinoball \u2013 consigue 32 conjuntos de ropa completamente nuevos!","datePublished":"2014-06-12T15:00:58+00:00","dateModified":"2014-06-12T15:52:13+00:00","mainEntityOfPage":{"@id":"https:\/\/dinostorm.com\/es\/el-desafio-dinoball-consigue-32-conjuntos-de-ropa-completamente-nuevos\/"},"wordCount":191,"image":{"@id":"https:\/\/dinostorm.com\/es\/el-desafio-dinoball-consigue-32-conjuntos-de-ropa-completamente-nuevos\/#primaryimage"},"thumbnailUrl":"https:\/\/dinostorm.com\/wp-content\/uploads\/2014\/06\/dino.storm_.dinoball.teaser.jpg","articleSection":["Noticias"],"inLanguage":"es-ES"},{"@type":"WebPage","@id":"https:\/\/dinostorm.com\/es\/el-desafio-dinoball-consigue-32-conjuntos-de-ropa-completamente-nuevos\/","url":"https:\/\/dinostorm.com\/es\/el-desafio-dinoball-consigue-32-conjuntos-de-ropa-completamente-nuevos\/","name":"El desaf\u00edo Dinoball \u2013 consigue 32 conjuntos de ropa completamente nuevos! - DinoStorm","isPartOf":{"@id":"https:\/\/dinostorm.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dinostorm.com\/es\/el-desafio-dinoball-consigue-32-conjuntos-de-ropa-completamente-nuevos\/#primaryimage"},"image":{"@id":"https:\/\/dinostorm.com\/es\/el-desafio-dinoball-consigue-32-conjuntos-de-ropa-completamente-nuevos\/#primaryimage"},"thumbnailUrl":"https:\/\/dinostorm.com\/wp-content\/uploads\/2014\/06\/dino.storm_.dinoball.teaser.jpg","datePublished":"2014-06-12T15:00:58+00:00","dateModified":"2014-06-12T15:52:13+00:00","author":{"@id":"https:\/\/dinostorm.com\/es\/#\/schema\/person\/99830ffffdd9f24640cefba5d01b851b"},"breadcrumb":{"@id":"https:\/\/dinostorm.com\/es\/el-desafio-dinoball-consigue-32-conjuntos-de-ropa-completamente-nuevos\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dinostorm.com\/es\/el-desafio-dinoball-consigue-32-conjuntos-de-ropa-completamente-nuevos\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/dinostorm.com\/es\/el-desafio-dinoball-consigue-32-conjuntos-de-ropa-completamente-nuevos\/#primaryimage","url":"https:\/\/dinostorm.com\/wp-content\/uploads\/2014\/06\/dino.storm_.dinoball.teaser.jpg","contentUrl":"https:\/\/dinostorm.com\/wp-content\/uploads\/2014\/06\/dino.storm_.dinoball.teaser.jpg","width":808,"height":327,"caption":"Dino Storm \u2013 Dinoball 2014"},{"@type":"BreadcrumbList","@id":"https:\/\/dinostorm.com\/es\/el-desafio-dinoball-consigue-32-conjuntos-de-ropa-completamente-nuevos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dinostorm.com\/es\/"},{"@type":"ListItem","position":2,"name":"El desaf\u00edo Dinoball \u2013 consigue 32 conjuntos de ropa completamente nuevos!"}]},{"@type":"WebSite","@id":"https:\/\/dinostorm.com\/es\/#website","url":"https:\/\/dinostorm.com\/es\/","name":"DinoStorm","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dinostorm.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/dinostorm.com\/es\/#\/schema\/person\/99830ffffdd9f24640cefba5d01b851b","name":"jgeisler","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/8c0d594e25fb116f72f06928d933d61ec76d18cc8ffa842a02afec16ad0940be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8c0d594e25fb116f72f06928d933d61ec76d18cc8ffa842a02afec16ad0940be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8c0d594e25fb116f72f06928d933d61ec76d18cc8ffa842a02afec16ad0940be?s=96&d=mm&r=g","caption":"jgeisler"}}]}},"_links":{"self":[{"href":"https:\/\/dinostorm.com\/es\/wp-json\/wp\/v2\/posts\/11032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dinostorm.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dinostorm.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dinostorm.com\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/dinostorm.com\/es\/wp-json\/wp\/v2\/comments?post=11032"}],"version-history":[{"count":0,"href":"https:\/\/dinostorm.com\/es\/wp-json\/wp\/v2\/posts\/11032\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dinostorm.com\/es\/wp-json\/wp\/v2\/media\/11048"}],"wp:attachment":[{"href":"https:\/\/dinostorm.com\/es\/wp-json\/wp\/v2\/media?parent=11032"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dinostorm.com\/es\/wp-json\/wp\/v2\/categories?post=11032"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dinostorm.com\/es\/wp-json\/wp\/v2\/tags?post=11032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}