{"id":10865,"date":"2014-04-11T16:00:43","date_gmt":"2014-04-11T14:00:43","guid":{"rendered":"http:\/\/dinostorm.com\/easter-dino-storm-crack-open-easter-eggs-special-easter-rewards-2"},"modified":"2014-04-11T16:36:11","modified_gmt":"2014-04-11T14:36:11","slug":"pascua-en-dino-storm-abre-los-huevos-de-pascua-para-obtener-recompensas-especiales","status":"publish","type":"post","link":"https:\/\/dinostorm.com\/es\/pascua-en-dino-storm-abre-los-huevos-de-pascua-para-obtener-recompensas-especiales\/","title":{"rendered":"Pascua en Dino Storm \u2013 \u00a1Abre los huevos de Pascua para obtener recompensas especiales!"},"content":{"rendered":"<h2 style=\"font-size: 26px; margin-top: 2px; margin-bottom: 8px; line-height: 32px;\">Encuentra Huevos de Pascua y Cucharas por todos los sitios<br \/>\n(excepto en el Ca\u00f1\u00f3n de Dinoville)<\/h2>\n<div style=\"margin-left: -11px; margin-right: 20px; float: left; width: 322px; text-align: left;\">\n<h3 class=\"highlight\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-10849 colorbox-10865\" style=\"margin-bottom: -20px; font-size: 14px; line-height: 1.5em;\" alt=\"Easter in Dino Storm \u2013 Easter Eggs\" src=\"http:\/\/dinostorm.com\/wp-content\/uploads\/2015\/04\/dino.storm_.easter.eggs_.png\" width=\"92\" height=\"69\" \/>Huevo de Pascua<\/h3>\n<div style=\"text-align: left; margin-left: 12px;\">Contiene una textura especial de Pascua para tu dinosaurio<\/div>\n<\/div>\n<div style=\"margin-left: 20px; margin-right: 20px; float: left; width: 302px; text-align: left;\">\n<h3 class=\"highlight\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-10902 colorbox-10865\" style=\"margin-bottom: -15px; font-size: 14px; line-height: 1.5em;\" alt=\"Easter in Dino Storm \u2013 Egg Spoon\" src=\"http:\/\/dinostorm.com\/wp-content\/uploads\/2015\/04\/event_easter_spoon1.png\" width=\"64\" height=\"64\" srcset=\"https:\/\/dinostorm.com\/wp-content\/uploads\/2015\/04\/event_easter_spoon1.png 64w, https:\/\/dinostorm.com\/wp-content\/uploads\/2015\/04\/event_easter_spoon1-36x36.png 36w\" sizes=\"auto, (max-width: 64px) 100vw, 64px\" \/>Cuchara para huevos<\/h3>\n<div style=\"text-align: left; margin-left: 4px;\">Necesaria para abrir Huevos de Pascua<\/div>\n<\/div>\n<h2 style=\"font-size: 26px; clear: both; padding-top: 48px; margin-bottom: 12px;\">\u00bfNecesitas m\u00e1s cucharas para huevos? \u00a1Cons\u00edguelas aqu\u00ed!<\/h2>\n<div>Encuentra m\u00e1s cucharas u obtenlas directamente de Eggy O&#8217;Spoone o ayudantes del evento de Pascua.<\/div>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-10888 colorbox-10865\" style=\"margin-right: 12px; margin-top: 16px;\" title=\"Easter in Dino Storm \u2013 World Map\" alt=\"Easter in Dino Storm \u2013 World Map\" src=\"http:\/\/dinostorm.com\/wp-content\/uploads\/2015\/04\/dino.storm_.easter.map_1.jpg\" width=\"532\" height=\"391\" srcset=\"https:\/\/dinostorm.com\/wp-content\/uploads\/2015\/04\/dino.storm_.easter.map_1.jpg 532w, https:\/\/dinostorm.com\/wp-content\/uploads\/2015\/04\/dino.storm_.easter.map_1-300x220.jpg 300w\" sizes=\"auto, (max-width: 532px) 100vw, 532px\" \/><\/p>\n<h3 style=\"margin-top: 42px; margin-bottom: 6px;\"><span style=\"color: #fcd789;\">\u2776<\/span> Eggy O&#8217;Spoone<\/h3>\n<p style=\"padding-left: 575px;\">Dinoville<\/p>\n<h3 style=\"margin-bottom: 6px;\"><span style=\"color: #fcd789;\">\u2777<\/span>\u00a0<span style=\"font-size: 15px;\">Nivel 25\u00a0Ayudante del evento de Pascua<\/span><\/h3>\n<p style=\"padding-left: 575px;\">La Polvareda<\/p>\n<h3 style=\"margin-bottom: 6px;\"><span style=\"color: #fcd789;\">\u2778<\/span>\u00a0<span style=\"font-size: 15px;\">Nivel 25\u00a0Ayudante del evento de Pascua<\/span><\/h3>\n<p style=\"padding-left: 575px;\">Selva Mok\u00f3n<\/p>\n<h3 style=\"margin-bottom: 6px;\"><span style=\"color: #fcd789;\">\u2779<\/span>\u00a0<span style=\"font-size: 15px;\">Nivel 40\u00a0Ayudante del evento de Pascua<\/span><\/h3>\n<p style=\"padding-left: 575px;\">Volc\u00e1n Verde<\/p>\n<h2 style=\"font-size: 26px; clear: both; padding-top: 28px;\">Ensilla tu dino y Celebra Pascua en Dino Storm<\/h2>\n<ul>\n<li>&#8220;Pascua en Dino Storm&#8221;\u00a0comienza el <span class=\"highlight\">16 de Abril a las 16:00h<\/span> hora del servidor*.<\/li>\n<li>El evento finaliza el <span class=\"highlight\">23 de Abril a las 23:59h<\/span> hora del servidor*.<\/li>\n<li>Encuentra Huevos de Pascua y Cucharas por todos los sitios (excepto en el Ca\u00f1\u00f3n de Dinoville).<\/li>\n<li>Abre Huevos de Pascua para obtener recompensas especiales.<\/li>\n<\/ul>\n<p>*\u00a0Horario Servidores USA: EDT | Horario Servidores EUR: CEST\u00a0| Horario Servidor Asia: CST<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Encuentra Huevos de Pascua y Cucharas por todos los sitios (excepto en el Ca\u00f1\u00f3n de Dinoville) Huevo de Pascua Contiene una textura especial de Pascua para tu dinosaurio Cuchara para huevos Necesaria para abrir Huevos [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":6016,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[14],"tags":[],"class_list":["post-10865","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pascua en Dino Storm \u2013 \u00a1Abre los huevos de Pascua para obtener recompensas especiales! - DinoStorm<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dinostorm.com\/es\/pascua-en-dino-storm-abre-los-huevos-de-pascua-para-obtener-recompensas-especiales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pascua en Dino Storm \u2013 \u00a1Abre los huevos de Pascua para obtener recompensas especiales! - DinoStorm\" \/>\n<meta property=\"og:description\" content=\"Encuentra Huevos de Pascua y Cucharas por todos los sitios (excepto en el Ca\u00f1\u00f3n de Dinoville) Huevo de Pascua Contiene una textura especial de Pascua para tu dinosaurio Cuchara para huevos Necesaria para abrir Huevos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dinostorm.com\/es\/pascua-en-dino-storm-abre-los-huevos-de-pascua-para-obtener-recompensas-especiales\/\" \/>\n<meta property=\"og:site_name\" content=\"DinoStorm\" \/>\n<meta property=\"article:published_time\" content=\"2014-04-11T14:00:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-04-11T14:36:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dinostorm.com\/wp-content\/uploads\/2013\/03\/dino.storm_.easter.2013.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"808\" \/>\n\t<meta property=\"og:image:height\" content=\"327\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"jgeisler\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"jgeisler\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/pascua-en-dino-storm-abre-los-huevos-de-pascua-para-obtener-recompensas-especiales\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/pascua-en-dino-storm-abre-los-huevos-de-pascua-para-obtener-recompensas-especiales\\\/\"},\"author\":{\"name\":\"jgeisler\",\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/#\\\/schema\\\/person\\\/99830ffffdd9f24640cefba5d01b851b\"},\"headline\":\"Pascua en Dino Storm \u2013 \u00a1Abre los huevos de Pascua para obtener recompensas especiales!\",\"datePublished\":\"2014-04-11T14:00:43+00:00\",\"dateModified\":\"2014-04-11T14:36:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/pascua-en-dino-storm-abre-los-huevos-de-pascua-para-obtener-recompensas-especiales\\\/\"},\"wordCount\":177,\"image\":{\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/pascua-en-dino-storm-abre-los-huevos-de-pascua-para-obtener-recompensas-especiales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dinostorm.com\\\/wp-content\\\/uploads\\\/2013\\\/03\\\/dino.storm_.easter.2013.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/pascua-en-dino-storm-abre-los-huevos-de-pascua-para-obtener-recompensas-especiales\\\/\",\"url\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/pascua-en-dino-storm-abre-los-huevos-de-pascua-para-obtener-recompensas-especiales\\\/\",\"name\":\"Pascua en Dino Storm \u2013 \u00a1Abre los huevos de Pascua para obtener recompensas especiales! - DinoStorm\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/pascua-en-dino-storm-abre-los-huevos-de-pascua-para-obtener-recompensas-especiales\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/pascua-en-dino-storm-abre-los-huevos-de-pascua-para-obtener-recompensas-especiales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dinostorm.com\\\/wp-content\\\/uploads\\\/2013\\\/03\\\/dino.storm_.easter.2013.jpg\",\"datePublished\":\"2014-04-11T14:00:43+00:00\",\"dateModified\":\"2014-04-11T14:36:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/#\\\/schema\\\/person\\\/99830ffffdd9f24640cefba5d01b851b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/pascua-en-dino-storm-abre-los-huevos-de-pascua-para-obtener-recompensas-especiales\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dinostorm.com\\\/es\\\/pascua-en-dino-storm-abre-los-huevos-de-pascua-para-obtener-recompensas-especiales\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/pascua-en-dino-storm-abre-los-huevos-de-pascua-para-obtener-recompensas-especiales\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dinostorm.com\\\/wp-content\\\/uploads\\\/2013\\\/03\\\/dino.storm_.easter.2013.jpg\",\"contentUrl\":\"https:\\\/\\\/dinostorm.com\\\/wp-content\\\/uploads\\\/2013\\\/03\\\/dino.storm_.easter.2013.jpg\",\"width\":808,\"height\":327,\"caption\":\"Easter in Dino Storm\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/pascua-en-dino-storm-abre-los-huevos-de-pascua-para-obtener-recompensas-especiales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pascua en Dino Storm \u2013 \u00a1Abre los huevos de Pascua para obtener recompensas especiales!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/\",\"name\":\"DinoStorm\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dinostorm.com\\\/es\\\/#\\\/schema\\\/person\\\/99830ffffdd9f24640cefba5d01b851b\",\"name\":\"jgeisler\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c0d594e25fb116f72f06928d933d61ec76d18cc8ffa842a02afec16ad0940be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c0d594e25fb116f72f06928d933d61ec76d18cc8ffa842a02afec16ad0940be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c0d594e25fb116f72f06928d933d61ec76d18cc8ffa842a02afec16ad0940be?s=96&d=mm&r=g\",\"caption\":\"jgeisler\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pascua en Dino Storm \u2013 \u00a1Abre los huevos de Pascua para obtener recompensas especiales! - DinoStorm","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dinostorm.com\/es\/pascua-en-dino-storm-abre-los-huevos-de-pascua-para-obtener-recompensas-especiales\/","og_locale":"es_ES","og_type":"article","og_title":"Pascua en Dino Storm \u2013 \u00a1Abre los huevos de Pascua para obtener recompensas especiales! - DinoStorm","og_description":"Encuentra Huevos de Pascua y Cucharas por todos los sitios (excepto en el Ca\u00f1\u00f3n de Dinoville) Huevo de Pascua Contiene una textura especial de Pascua para tu dinosaurio Cuchara para huevos Necesaria para abrir Huevos [&hellip;]","og_url":"https:\/\/dinostorm.com\/es\/pascua-en-dino-storm-abre-los-huevos-de-pascua-para-obtener-recompensas-especiales\/","og_site_name":"DinoStorm","article_published_time":"2014-04-11T14:00:43+00:00","article_modified_time":"2014-04-11T14:36:11+00:00","og_image":[{"width":808,"height":327,"url":"https:\/\/dinostorm.com\/wp-content\/uploads\/2013\/03\/dino.storm_.easter.2013.jpg","type":"image\/jpeg"}],"author":"jgeisler","twitter_misc":{"Escrito por":"jgeisler","Tiempo de lectura":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dinostorm.com\/es\/pascua-en-dino-storm-abre-los-huevos-de-pascua-para-obtener-recompensas-especiales\/#article","isPartOf":{"@id":"https:\/\/dinostorm.com\/es\/pascua-en-dino-storm-abre-los-huevos-de-pascua-para-obtener-recompensas-especiales\/"},"author":{"name":"jgeisler","@id":"https:\/\/dinostorm.com\/es\/#\/schema\/person\/99830ffffdd9f24640cefba5d01b851b"},"headline":"Pascua en Dino Storm \u2013 \u00a1Abre los huevos de Pascua para obtener recompensas especiales!","datePublished":"2014-04-11T14:00:43+00:00","dateModified":"2014-04-11T14:36:11+00:00","mainEntityOfPage":{"@id":"https:\/\/dinostorm.com\/es\/pascua-en-dino-storm-abre-los-huevos-de-pascua-para-obtener-recompensas-especiales\/"},"wordCount":177,"image":{"@id":"https:\/\/dinostorm.com\/es\/pascua-en-dino-storm-abre-los-huevos-de-pascua-para-obtener-recompensas-especiales\/#primaryimage"},"thumbnailUrl":"https:\/\/dinostorm.com\/wp-content\/uploads\/2013\/03\/dino.storm_.easter.2013.jpg","articleSection":["Noticias"],"inLanguage":"es-ES"},{"@type":"WebPage","@id":"https:\/\/dinostorm.com\/es\/pascua-en-dino-storm-abre-los-huevos-de-pascua-para-obtener-recompensas-especiales\/","url":"https:\/\/dinostorm.com\/es\/pascua-en-dino-storm-abre-los-huevos-de-pascua-para-obtener-recompensas-especiales\/","name":"Pascua en Dino Storm \u2013 \u00a1Abre los huevos de Pascua para obtener recompensas especiales! - DinoStorm","isPartOf":{"@id":"https:\/\/dinostorm.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dinostorm.com\/es\/pascua-en-dino-storm-abre-los-huevos-de-pascua-para-obtener-recompensas-especiales\/#primaryimage"},"image":{"@id":"https:\/\/dinostorm.com\/es\/pascua-en-dino-storm-abre-los-huevos-de-pascua-para-obtener-recompensas-especiales\/#primaryimage"},"thumbnailUrl":"https:\/\/dinostorm.com\/wp-content\/uploads\/2013\/03\/dino.storm_.easter.2013.jpg","datePublished":"2014-04-11T14:00:43+00:00","dateModified":"2014-04-11T14:36:11+00:00","author":{"@id":"https:\/\/dinostorm.com\/es\/#\/schema\/person\/99830ffffdd9f24640cefba5d01b851b"},"breadcrumb":{"@id":"https:\/\/dinostorm.com\/es\/pascua-en-dino-storm-abre-los-huevos-de-pascua-para-obtener-recompensas-especiales\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dinostorm.com\/es\/pascua-en-dino-storm-abre-los-huevos-de-pascua-para-obtener-recompensas-especiales\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/dinostorm.com\/es\/pascua-en-dino-storm-abre-los-huevos-de-pascua-para-obtener-recompensas-especiales\/#primaryimage","url":"https:\/\/dinostorm.com\/wp-content\/uploads\/2013\/03\/dino.storm_.easter.2013.jpg","contentUrl":"https:\/\/dinostorm.com\/wp-content\/uploads\/2013\/03\/dino.storm_.easter.2013.jpg","width":808,"height":327,"caption":"Easter in Dino Storm"},{"@type":"BreadcrumbList","@id":"https:\/\/dinostorm.com\/es\/pascua-en-dino-storm-abre-los-huevos-de-pascua-para-obtener-recompensas-especiales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dinostorm.com\/es\/"},{"@type":"ListItem","position":2,"name":"Pascua en Dino Storm \u2013 \u00a1Abre los huevos de Pascua para obtener recompensas especiales!"}]},{"@type":"WebSite","@id":"https:\/\/dinostorm.com\/es\/#website","url":"https:\/\/dinostorm.com\/es\/","name":"DinoStorm","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dinostorm.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/dinostorm.com\/es\/#\/schema\/person\/99830ffffdd9f24640cefba5d01b851b","name":"jgeisler","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/8c0d594e25fb116f72f06928d933d61ec76d18cc8ffa842a02afec16ad0940be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8c0d594e25fb116f72f06928d933d61ec76d18cc8ffa842a02afec16ad0940be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8c0d594e25fb116f72f06928d933d61ec76d18cc8ffa842a02afec16ad0940be?s=96&d=mm&r=g","caption":"jgeisler"}}]}},"_links":{"self":[{"href":"https:\/\/dinostorm.com\/es\/wp-json\/wp\/v2\/posts\/10865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dinostorm.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dinostorm.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dinostorm.com\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/dinostorm.com\/es\/wp-json\/wp\/v2\/comments?post=10865"}],"version-history":[{"count":0,"href":"https:\/\/dinostorm.com\/es\/wp-json\/wp\/v2\/posts\/10865\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dinostorm.com\/es\/wp-json\/wp\/v2\/media\/6016"}],"wp:attachment":[{"href":"https:\/\/dinostorm.com\/es\/wp-json\/wp\/v2\/media?parent=10865"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dinostorm.com\/es\/wp-json\/wp\/v2\/categories?post=10865"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dinostorm.com\/es\/wp-json\/wp\/v2\/tags?post=10865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}