{"id":1335,"date":"2011-08-10T08:40:50","date_gmt":"2011-08-10T06:40:50","guid":{"rendered":"http:\/\/dinostorm.com\/die-zeichen-stehen-auf-sturm"},"modified":"2018-02-01T14:47:22","modified_gmt":"2018-02-01T12:47:22","slug":"die-zeichen-stehen-auf-sturm","status":"publish","type":"post","link":"https:\/\/dinostorm.com\/de\/die-zeichen-stehen-auf-sturm\/","title":{"rendered":"Die Zeichen stehen auf Sturm"},"content":{"rendered":"<p>Heute geht Dino Storm mit einer brandneuen Website online. Au\u00dferdem bieten wir erstmalig genauere Einblicke, was die furchtlosen Abenteurer in DinoVille erwartet. Dazu gibt es neue Screenshots und Bilder aus dem Spiel.<!--more--><\/p>\n<p>In der Kleinstadt DinoVille herrscht Aufregung. Eine Gruppe von Rangern hat im Norden Gold gefunden. Die M\u00e4nner kehren mit gro\u00dfem Reichtum von ihrer Reise aus dem Umland in die Stadt heim, im \u00f6rtlichen Saloon protzen Sie mit ihrem neuen Reichtum. Die Nachricht verbreitet sich wie ein Lauffeuer im ganzen Land. Es wird nicht mehr lange dauern, bis waghalsige Abenteurer, umtriebige Goldsucher und fiese R\u00e4uberbanden aus dem ganzen Land in der Kleinstadt auftauchen.<\/p>\n<p>Im 3D-Abenteuer Dino Storm macht ihr euch auf den Weg nach DinoVille, auf der Suche nach Anerkennung und Reichtum. Ihr besch\u00fctzt die Stadt vor gewaltigen Dinosaurier-Herden, erbarmungslosen R\u00e4uberbanden und anderem fiesen Gesindel. Oder ihr gr\u00fcndet eine eigene Bande und beginnt selbst mit der Errichtung einer Goldmine, immer bedroht von anderen Goldsuchern. Im Rathaus der Stadt ringen die ber\u00fchmtesten Spieler um privilegierte \u00c4mter und nur die Besten werden es schaffen, zum Deputy oder Sheriff aufzusteigen.<\/p>\n<p>Dino Storm ist komplett kostenlos spielbar und bietet wundersch\u00f6ne, detaillierte 3D-Grafik ohne Installation direkt im Browser. Um schon bei der Closed Beta dabei zu sein, ist nur eine Registrierung auf DinoStorm.com notwendig. Ihr werdet dann rechtzeitig informiert, wenn es richtig los geht.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Heute geht Dino Storm mit einer brandneuen Website online. Au\u00dferdem bieten wir erstmalig genauere Einblicke, was die furchtlosen Abenteurer in DinoVille erwartet. Dazu gibt es neue Screenshots und Bilder aus dem Spiel.<\/p>\n","protected":false},"author":26,"featured_media":375,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[13],"tags":[],"class_list":["post-1335","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-neuigkeiten"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die Zeichen stehen auf Sturm - DinoStorm<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dinostorm.com\/de\/die-zeichen-stehen-auf-sturm\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die Zeichen stehen auf Sturm - DinoStorm\" \/>\n<meta property=\"og:description\" content=\"Heute geht Dino Storm mit einer brandneuen Website online. Au\u00dferdem bieten wir erstmalig genauere Einblicke, was die furchtlosen Abenteurer in DinoVille erwartet. Dazu gibt es neue Screenshots und Bilder aus dem Spiel.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dinostorm.com\/de\/die-zeichen-stehen-auf-sturm\/\" \/>\n<meta property=\"og:site_name\" content=\"DinoStorm\" \/>\n<meta property=\"article:published_time\" content=\"2011-08-10T06:40:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-02-01T12:47:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dinostorm.com\/wp-content\/uploads\/2011\/08\/teaser_05.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alexandre Maia\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alexandre Maia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dinostorm.com\\\/de\\\/die-zeichen-stehen-auf-sturm\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dinostorm.com\\\/de\\\/die-zeichen-stehen-auf-sturm\\\/\"},\"author\":{\"name\":\"Alexandre Maia\",\"@id\":\"https:\\\/\\\/dinostorm.com\\\/de\\\/#\\\/schema\\\/person\\\/e95cdfcb946945943679f1c51632fcfd\"},\"headline\":\"Die Zeichen stehen auf Sturm\",\"datePublished\":\"2011-08-10T06:40:50+00:00\",\"dateModified\":\"2018-02-01T12:47:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dinostorm.com\\\/de\\\/die-zeichen-stehen-auf-sturm\\\/\"},\"wordCount\":235,\"image\":{\"@id\":\"https:\\\/\\\/dinostorm.com\\\/de\\\/die-zeichen-stehen-auf-sturm\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dinostorm.com\\\/wp-content\\\/uploads\\\/2011\\\/08\\\/teaser_05.jpg\",\"articleSection\":[\"Neuigkeiten\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dinostorm.com\\\/de\\\/die-zeichen-stehen-auf-sturm\\\/\",\"url\":\"https:\\\/\\\/dinostorm.com\\\/de\\\/die-zeichen-stehen-auf-sturm\\\/\",\"name\":\"Die Zeichen stehen auf Sturm - DinoStorm\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dinostorm.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dinostorm.com\\\/de\\\/die-zeichen-stehen-auf-sturm\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dinostorm.com\\\/de\\\/die-zeichen-stehen-auf-sturm\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dinostorm.com\\\/wp-content\\\/uploads\\\/2011\\\/08\\\/teaser_05.jpg\",\"datePublished\":\"2011-08-10T06:40:50+00:00\",\"dateModified\":\"2018-02-01T12:47:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dinostorm.com\\\/de\\\/#\\\/schema\\\/person\\\/e95cdfcb946945943679f1c51632fcfd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dinostorm.com\\\/de\\\/die-zeichen-stehen-auf-sturm\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dinostorm.com\\\/de\\\/die-zeichen-stehen-auf-sturm\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/dinostorm.com\\\/de\\\/die-zeichen-stehen-auf-sturm\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dinostorm.com\\\/wp-content\\\/uploads\\\/2011\\\/08\\\/teaser_05.jpg\",\"contentUrl\":\"https:\\\/\\\/dinostorm.com\\\/wp-content\\\/uploads\\\/2011\\\/08\\\/teaser_05.jpg\",\"width\":640,\"height\":250},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dinostorm.com\\\/de\\\/die-zeichen-stehen-auf-sturm\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dinostorm.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die Zeichen stehen auf Sturm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dinostorm.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/dinostorm.com\\\/de\\\/\",\"name\":\"DinoStorm\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dinostorm.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dinostorm.com\\\/de\\\/#\\\/schema\\\/person\\\/e95cdfcb946945943679f1c51632fcfd\",\"name\":\"Alexandre Maia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ea2563be3235f7f91ee620bf5ce2037cbf7d378034d005466d7f43ca72739ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ea2563be3235f7f91ee620bf5ce2037cbf7d378034d005466d7f43ca72739ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ea2563be3235f7f91ee620bf5ce2037cbf7d378034d005466d7f43ca72739ce?s=96&d=mm&r=g\",\"caption\":\"Alexandre Maia\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die Zeichen stehen auf Sturm - DinoStorm","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dinostorm.com\/de\/die-zeichen-stehen-auf-sturm\/","og_locale":"de_DE","og_type":"article","og_title":"Die Zeichen stehen auf Sturm - DinoStorm","og_description":"Heute geht Dino Storm mit einer brandneuen Website online. Au\u00dferdem bieten wir erstmalig genauere Einblicke, was die furchtlosen Abenteurer in DinoVille erwartet. Dazu gibt es neue Screenshots und Bilder aus dem Spiel.","og_url":"https:\/\/dinostorm.com\/de\/die-zeichen-stehen-auf-sturm\/","og_site_name":"DinoStorm","article_published_time":"2011-08-10T06:40:50+00:00","article_modified_time":"2018-02-01T12:47:22+00:00","og_image":[{"width":640,"height":250,"url":"https:\/\/dinostorm.com\/wp-content\/uploads\/2011\/08\/teaser_05.jpg","type":"image\/jpeg"}],"author":"Alexandre Maia","twitter_misc":{"Verfasst von":"Alexandre Maia","Gesch\u00e4tzte Lesezeit":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dinostorm.com\/de\/die-zeichen-stehen-auf-sturm\/#article","isPartOf":{"@id":"https:\/\/dinostorm.com\/de\/die-zeichen-stehen-auf-sturm\/"},"author":{"name":"Alexandre Maia","@id":"https:\/\/dinostorm.com\/de\/#\/schema\/person\/e95cdfcb946945943679f1c51632fcfd"},"headline":"Die Zeichen stehen auf Sturm","datePublished":"2011-08-10T06:40:50+00:00","dateModified":"2018-02-01T12:47:22+00:00","mainEntityOfPage":{"@id":"https:\/\/dinostorm.com\/de\/die-zeichen-stehen-auf-sturm\/"},"wordCount":235,"image":{"@id":"https:\/\/dinostorm.com\/de\/die-zeichen-stehen-auf-sturm\/#primaryimage"},"thumbnailUrl":"https:\/\/dinostorm.com\/wp-content\/uploads\/2011\/08\/teaser_05.jpg","articleSection":["Neuigkeiten"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/dinostorm.com\/de\/die-zeichen-stehen-auf-sturm\/","url":"https:\/\/dinostorm.com\/de\/die-zeichen-stehen-auf-sturm\/","name":"Die Zeichen stehen auf Sturm - DinoStorm","isPartOf":{"@id":"https:\/\/dinostorm.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dinostorm.com\/de\/die-zeichen-stehen-auf-sturm\/#primaryimage"},"image":{"@id":"https:\/\/dinostorm.com\/de\/die-zeichen-stehen-auf-sturm\/#primaryimage"},"thumbnailUrl":"https:\/\/dinostorm.com\/wp-content\/uploads\/2011\/08\/teaser_05.jpg","datePublished":"2011-08-10T06:40:50+00:00","dateModified":"2018-02-01T12:47:22+00:00","author":{"@id":"https:\/\/dinostorm.com\/de\/#\/schema\/person\/e95cdfcb946945943679f1c51632fcfd"},"breadcrumb":{"@id":"https:\/\/dinostorm.com\/de\/die-zeichen-stehen-auf-sturm\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dinostorm.com\/de\/die-zeichen-stehen-auf-sturm\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/dinostorm.com\/de\/die-zeichen-stehen-auf-sturm\/#primaryimage","url":"https:\/\/dinostorm.com\/wp-content\/uploads\/2011\/08\/teaser_05.jpg","contentUrl":"https:\/\/dinostorm.com\/wp-content\/uploads\/2011\/08\/teaser_05.jpg","width":640,"height":250},{"@type":"BreadcrumbList","@id":"https:\/\/dinostorm.com\/de\/die-zeichen-stehen-auf-sturm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dinostorm.com\/de\/"},{"@type":"ListItem","position":2,"name":"Die Zeichen stehen auf Sturm"}]},{"@type":"WebSite","@id":"https:\/\/dinostorm.com\/de\/#website","url":"https:\/\/dinostorm.com\/de\/","name":"DinoStorm","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dinostorm.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Person","@id":"https:\/\/dinostorm.com\/de\/#\/schema\/person\/e95cdfcb946945943679f1c51632fcfd","name":"Alexandre Maia","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/secure.gravatar.com\/avatar\/5ea2563be3235f7f91ee620bf5ce2037cbf7d378034d005466d7f43ca72739ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5ea2563be3235f7f91ee620bf5ce2037cbf7d378034d005466d7f43ca72739ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5ea2563be3235f7f91ee620bf5ce2037cbf7d378034d005466d7f43ca72739ce?s=96&d=mm&r=g","caption":"Alexandre Maia"}}]}},"_links":{"self":[{"href":"https:\/\/dinostorm.com\/de\/wp-json\/wp\/v2\/posts\/1335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dinostorm.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dinostorm.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dinostorm.com\/de\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/dinostorm.com\/de\/wp-json\/wp\/v2\/comments?post=1335"}],"version-history":[{"count":0,"href":"https:\/\/dinostorm.com\/de\/wp-json\/wp\/v2\/posts\/1335\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dinostorm.com\/de\/wp-json\/wp\/v2\/media\/375"}],"wp:attachment":[{"href":"https:\/\/dinostorm.com\/de\/wp-json\/wp\/v2\/media?parent=1335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dinostorm.com\/de\/wp-json\/wp\/v2\/categories?post=1335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dinostorm.com\/de\/wp-json\/wp\/v2\/tags?post=1335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}